{"id":3649,"date":"2013-11-30T09:00:37","date_gmt":"2013-11-30T09:00:37","guid":{"rendered":"http:\/\/www.levpn.fr\/?p=3649"},"modified":"2020-06-25T16:50:46","modified_gmt":"2020-06-25T14:50:46","slug":"les-filtres-de-censure-de-skype-en-chine-supprimes","status":"publish","type":"post","link":"https:\/\/www.le-vpn.com\/fr\/les-filtres-de-censure-de-skype-en-chine-supprimes\/","title":{"rendered":"Les filtres de censure de Skype en Chine supprim\u00e9s ?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p style=\"text-align: left;\" align=\"center\">Apr\u00e8s avoir mis fin au partenariat de Skype avec Tom Online, Microsoft enl\u00e8verait l&#8217;ensemble des filtres de censure pour les internautes chinois.<\/p>\n<p>Le logiciel de VoIP Skype a une version sp\u00e9cifique pour la Chine, compte tenu de la censure gouvernementale. Pendant plusieurs ann\u00e9es Skype fonctionnait via TOM Online, le fournisseur d\u2019acc\u00e8s chinois. Or, en 2008, des chercheurs avaient identifi\u00e9 que les conversations tenues via la messagerie instantan\u00e9e \u00e9crite du logiciel Skype \u00e9taient surveill\u00e9es et censur\u00e9es.\u00a0 Mais l&#8217;accord sign\u00e9 en 2006 avec Skype s&#8217;\u00e9tait achev\u00e9 et n&#8217;avait pas \u00e9t\u00e9 renouvel\u00e9 par Microsoft qui a achet\u00e9 Skype en 2011. D\u00e9but 2013, plusieurs organisations de d\u00e9fense de la vie priv\u00e9e et activistes avaient exprim\u00e9 leurs craintes et demand\u00e9 plus de transparence \u00e0 Microsoft.<\/p>\n<p>Microsoft vient d\u2019annoncer avoir mis un terme au partenariat avec Tom Online pour former une nouvelle <i>joint-venture<\/i> avec Guangming Founder. Une mise \u00e0 jour du logiciel serait en cours de d\u00e9ploiement aupr\u00e8s des internautes chinois. Sur son blog officiel, l&#8217;\u00e9quipe de Skype explique que son nouveau partenaire excelle dans le domaine des technologies de communication mobiles.<\/p>\n<p>Et selon un rapport du site GreatFire.org, qui surveille le degr\u00e9 de censure sur le net chinois, Microsoft aurait supprim\u00e9 tous les filtres mis en place par les autorit\u00e9s ainsi que ceux permettant de surveiller les \u00e9changes des utilisateurs. Les informations de connexion, les appels t\u00e9l\u00e9phoniques ainsi que les messages instantan\u00e9s seraient tous chiffr\u00e9s et transiteraient sans interm\u00e9diaire vers les serveurs de Microsoft en HTTPS (mode s\u00e9curis\u00e9).Ces informations \u00e9taient jusque-l\u00e0 g\u00e9r\u00e9es via les serveurs de TOM Online.<\/p>\n<p>Microsoft n&#8217;a, quant \u00e0 lui, donn\u00e9 aucune pr\u00e9cision sur cette nouvelle version de Skype, dont l&#8217;\u00e9dition Windows (uniquement) est h\u00e9berg\u00e9e sur un sous-domaine de Guangming Founder. Pour l&#8217;heure, on ne sait donc pas si celle-ci est identique aux autres versions, ni si elle inclue des m\u00e9canismes de surveillance sp\u00e9cifique. On sait juste que la signature du logiciel a \u00e9t\u00e9 effectu\u00e9e par Microsoft et contr\u00f4le donc son code source. Ces changements pourraient aussi signifier la fin de Windows Live Messenger en Chine, le seul pays o\u00f9 la messagerie est encore op\u00e9rationnelle.<\/p>\n<p>Pour \u00e9viter toute censure sur Internet, optez pour les services d\u2019un <a href=\"http:\/\/www.le-vpn.com\/fr\/\">VPN<\/a> qui vous permettent de choisir votre pays de connexion. Que vous viviez en Chine ou ailleurs, vous pouvez choisir de domicilier votre connexion dans l\u2019un des 20 pays o\u00f9 l\u2019acc\u00e8s n\u2019est pas restreint. Vous pourrez ainsi acc\u00e9der dans l\u2019<a href=\"http:\/\/www.le-vpn.com\/fr\/surfez-anonymement\">anonymat<\/a> aux sites de votre choix, sans subir la censure ni les repr\u00e9sailles qu\u2019elle peut impliquer. Optez d\u00e8s aujourd\u2019hui pour Le VPN, pour surfer en toute s\u00e9curit\u00e9.<\/p>\n[vc_row][vc_column]<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-766a04cc1b55353\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div data-id=\"mpc_callout-616a04cc1b5304f\" class=\"mpc-callout mpc-init mpc-callout--style_1 \"><div class=\"mpc-callout__icon-wrap mpc-icon--image\"><div class=\"mpc-callout__icon\"><i class=\"mpc-transition \"><img decoding=\"async\" class=\"\" src=\"https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2025\/09\/exclusive-deal.png\" width=\"100\" height=\"100\" alt=\"exclusive-deal\" title=\"exclusive-deal\" loading=\"lazy\"><\/i><\/div><\/div><div class=\"mpc-callout__content\"><h3 class=\"mpc-callout__heading mpc-typography--preset_1\">OFFRE EXCLUSIVE<\/h3><div data-id=\"mpc_divider-216a04cc1b53122\" class=\"mpc-divider-wrap\"><div class=\"mpc-divider mpc-init mpc-align--center mpc-disable--left \"><div class=\"mpc-divider__line mpc-side--left\"><span><\/span><\/div><div class=\"mpc-divider__line mpc-side--right\"><span><\/span><\/div><\/div><\/div><div class=\"mpc-callout__description\"><p>LES 3 PREMI&Egrave;RES ANN&Eacute;ES &Agrave; 2,22 &euro;\/MOIS<\/p>\n<\/div><\/div><div class=\"mpc-callout__button\"><a href=\"https:\/\/www.le-vpn.com\/fr\/acheter-le-vpn\/\" title=\"\" data-id=\"mpc_button-826a04cc1b530d2\" class=\"mpc-button mpc-init mpc-transition mpc-typography--preset_2 \"><div class=\"mpc-button__content mpc-effect-type--none mpc-effect-side--none\"><span class=\"mpc-button__title mpc-transition\">PROFITEZ EN<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1725366294400 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-126a04cc1b53ce2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036137534\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>PAS DE JOURNAL<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1699541136156\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>100+ LOCALISATIONS<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-376a04cc1b54172\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036153466\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>P2P autoris&eacute;<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036161279\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Facile &agrave; utiliser<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-76a04cc1b545a1\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1622661737627\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:13px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Garantie de 30 Jours<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036177713\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Assistance amicale<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-776a04cc1b5496a\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036185445\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Bitcoin accept&eacute;<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036194514\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Vitesse de l'&eacute;clair<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1701699917169 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-696a04cc1b55f26\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\r\n<\/div>[\/vc_column][\/vc_row]<\/div>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s avoir mis fin au partenariat de Skype avec Tom Online, Microsoft enl\u00e8verait l&#8217;ensemble des filtres de censure pour les internautes chinois. Le logiciel de VoIP Skype a une version sp\u00e9cifique pour la Chine, compte tenu de la censure gouvernementale. Pendant plusieurs ann\u00e9es Skype fonctionnait via TOM Online, le fournisseur d\u2019acc\u00e8s chinois. Or, en 2008,<\/p>\n","protected":false},"author":10,"featured_media":3650,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_metadesc":"Microsoft qui a mis un terme \u00e0 son partenariat avec Tom Online en Chine aurait aussi supprim\u00e9 les filtres de censure de Skype","footnotes":""},"categories":[833],"tags":[325,290,267,91,269,248,281,272],"yst_prominent_words":[1404,1770,1459,1157,7892,3191,7885,1991,7882,2205,2044,7889,4752,1595,2428,7893,4801,7881,3628,1167],"class_list":["post-3649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog_old","tag-cacher-son-adresse-ip","tag-censure-internet","tag-censure-internet-en-chine","tag-cyberdata","tag-cyberespionnage","tag-cybersecurite","tag-masquer-son-adresse-ip","tag-serveurs-le-vpn"],"_links":{"self":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/3649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/comments?post=3649"}],"version-history":[{"count":5,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/3649\/revisions"}],"predecessor-version":[{"id":6811,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/3649\/revisions\/6811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/media\/3650"}],"wp:attachment":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/media?parent=3649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/categories?post=3649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/tags?post=3649"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=3649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}