{"id":32636,"date":"2020-03-26T08:00:35","date_gmt":"2020-03-26T06:00:35","guid":{"rendered":"https:\/\/www.le-vpn.com\/fr\/?p=32636"},"modified":"2020-04-05T02:00:35","modified_gmt":"2020-04-05T00:00:35","slug":"ecole-en-ligne","status":"publish","type":"post","link":"https:\/\/www.le-vpn.com\/fr\/ecole-en-ligne\/","title":{"rendered":"\u00c9cole en ligne : quels risques pour la sant\u00e9 mentale\u2009?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>Les cours en ligne ont commenc\u00e9, et il est d\u00e9sormais clair que les \u00e9coles physiques n\u2019existent pas seulement pour \u00e9duquer les enfants, mais aussi pour pr\u00e9server la sant\u00e9 mentale des parents. Quoi qu\u2019il en soit, la quarantaine que nous devons endurer pendant cette crise du Covid-19 va poser quelques probl\u00e8mes, mais aussi apporter certains avantages.<\/p>\n<p>La premi\u00e8re s\u00e9rie de probl\u00e8mes \u00e0 r\u00e9soudre est d\u2019ordre technique. La distanciation sociale signifie notamment que vous devez acheter un peu plus de nourriture que d\u2019habitude pour ne pas aller trop souvent au supermarch\u00e9. Et \u00e0 moins que vous ne soyez un extraterrestre avec un r\u00e9gime alimentaire strictement bas\u00e9 sur la cellulose, le papier toilette ne sera pas suffisant.<\/p>\n<p>Par ailleurs, certains probl\u00e8mes peuvent survenir lorsque tout le monde utilise internet en m\u00eame temps. Les r\u00e9seaux peuvent \u00eatre surcharg\u00e9s et les serveurs ne plus fonctionner aussi bien qu\u2019avant. Il existe \u00e9galement des risques pour la <a href=\"https:\/\/www.le-vpn.com\/fr\/10-conseils-cybersecurite-parents\/\">cybers\u00e9curit\u00e9 des enfants<\/a>, car tout le monde sait quand ils seront en ligne.<\/p>\n<p>Heureusement, gr\u00e2ce aux meilleurs fournisseurs de VPN comme Le VPN, nous pouvons modifier la localisation de notre serveur sans changer d\u2019emplacement physiquement. Ainsi, nous pouvons profiter d\u2019internet librement et en toute s\u00e9curit\u00e9.<\/p>\n<p>Enfin, gr\u00e2ce \u00e0 un solide dispositif de cybers\u00e9curit\u00e9, nous pourrons nous d\u00e9tendre en regardant des films, des s\u00e9ries et des jeux, une chose essentielle pour notre sant\u00e9 mentale et notre bonheur \u00e0 la maison.<\/p>\n<h3>Que savons-nous\u2009?<\/h3>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-32651\" src=\"https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2020\/03\/Virtual-Classes-are-not-Only-Risky-for-Parents-Mental-Health-1200x628-1.jpg\" alt=\"\u00c9cole en ligne : quels risques pour la sant\u00e9 mentale\u2009? | Le VPN\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2020\/03\/Virtual-Classes-are-not-Only-Risky-for-Parents-Mental-Health-1200x628-1.jpg 1200w, https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2020\/03\/Virtual-Classes-are-not-Only-Risky-for-Parents-Mental-Health-1200x628-1-300x157.jpg 300w, https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2020\/03\/Virtual-Classes-are-not-Only-Risky-for-Parents-Mental-Health-1200x628-1-1024x536.jpg 1024w, https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2020\/03\/Virtual-Classes-are-not-Only-Risky-for-Parents-Mental-Health-1200x628-1-768x402.jpg 768w, https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2020\/03\/Virtual-Classes-are-not-Only-Risky-for-Parents-Mental-Health-1200x628-1-500x262.jpg 500w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Au moins pour plusieurs semaines, les \u00e9coles passeront \u00e0 des salles de classe virtuelles. Au moyen de logiciels tels que MicrosoftTeam ou Skype, les enseignants tenteront de dispenser le programme comme si tous les enfants \u00e9taient en classe.<\/p>\n<p>Une p\u00e9riode d\u2019adaptation est \u00e9videmment n\u00e9cessaire avant de pouvoir v\u00e9rifier si ce mod\u00e8le est plus ou moins performant que les salles de classe traditionnelles. Il se pourrait m\u00eame que les enfants soient plus dispos\u00e9s \u00e0 suivre leurs cours dans le confort de leur foyer.<\/p>\n<p>Mais il y a aussi le facteur de socialisation, car passer du temps avec des amis est crucial pour le d\u00e9veloppement de l\u2019enfant. Actuellement, les parents et les fr\u00e8res et s\u0153urs doivent remplir ce r\u00f4le social, et cela sera sans doute b\u00e9n\u00e9fique.<\/p>\n<p>Autrement, comme les enfants passeront beaucoup de temps en ligne, ils pourraient bien tomber sur des <a href=\"https:\/\/www.le-vpn.com\/fr\/applications-dangereuses-reseaux-sociaux\/\">applications de m\u00e9dias sociaux dangereuses<\/a>, et vous pourriez \u00eatre pris au d\u00e9pourvu par ce qu\u2019ils pourraient y trouver.<\/p>\n<h4>Difficult\u00e9s techniques<\/h4>\n<p>M\u00eame si nous n\u2019avons pas le <a href=\"https:\/\/www.le-vpn.com\/fr\/top-10-pays-debits-internet-plus-rapides\/\">meilleur internet du monde<\/a>, les connexions internet en France sont globalement satisfaisantes. Toutefois, le syst\u00e8me n\u2019a pas \u00e9t\u00e9 pas con\u00e7u pour servir tout le monde en m\u00eame temps. Auparavant, y compris aux heures de pointe, un maximum de 70\u00a0% de la population \u00e9tait concern\u00e9. C\u2019est pourquoi des ralentissements sont en ce moment in\u00e9vitables.<\/p>\n<p>Si tout le monde se connecte en m\u00eame temps pour \u00e9tudier et travailler, nous aurons tous une vitesse r\u00e9duite. Les serveurs qui h\u00e9bergent ces informations ne sont pas faits pour envoyer autant de donn\u00e9es simultan\u00e9ment.<\/p>\n<p>Il est peu probable que les principaux services tels que Google, Facebook ou Microsoft soient paralys\u00e9s, mais ils pourraient tout de m\u00eame subir des ralentissements ou des retards localement.<\/p>\n<h4>Changer d\u2019emplacement<\/h4>\n<p>Dans certains pays, le Covid-19 ne constitue pas pour le moment un probl\u00e8me aussi important qu\u2019en France et en Europe. Les petits pays isol\u00e9s ou ceux qui comptent une faible densit\u00e9 de population sont beaucoup plus r\u00e9sistants \u00e0 la propagation du virus.<\/p>\n<p>Par cons\u00e9quent, vous pouvez utiliser un VPN pour vous connecter \u00e0 partir de ces pays et contourner les obstacles. Si votre r\u00e9seau local est soumis \u00e0 une forte pression, il se peut que des probl\u00e8mes apparaissent, mais votre acc\u00e8s aux ressources en ligne sera le m\u00eame.<\/p>\n<h3>Temps pass\u00e9 en ligne et hors-ligne<\/h3>\n<p>Quand vous <a href=\"https:\/\/www.le-vpn.com\/fr\/covid-19\/\">travaillez de chez vous<\/a>, il est facile de tomber dans le pi\u00e8ge du surmenage. En outre, vous pourriez \u00eatre tent\u00e9 de laisser vos enfants passer plus de temps que n\u00e9cessaire en ligne.<\/p>\n<p>Non seulement l\u2019utilisation continue d\u2019internet peut augmenter les risques de <a href=\"https:\/\/www.le-vpn.com\/fr\/cyberharcelement\/\">cyberharc\u00e8lement<\/a> et des cons\u00e9quences qui en d\u00e9coulent, mais elle peut aussi entra\u00eener de multiples probl\u00e8mes m\u00e9dicaux. Assurez-vous que votre enfant voit aussi des choses qui ne soient pas que num\u00e9riques.<\/p>\n<p>Si vous passez du temps en famille, vous parviendrez sans doute \u00e0 maintenir un bon \u00e9quilibre entre vie priv\u00e9e et libert\u00e9, m\u00eame lorsque vous \u00eates coinc\u00e9 chez vous.<\/p>\n<h4>Pr\u00e9servez une certaine intimit\u00e9<\/h4>\n<p>Pour vous \u00e9videmment, mais aussi pour vos compagnons de quarantaine.<\/p>\n<p>Lorsque vos enfants sont \u00ab\u2009\u00e0 l\u2019\u00e9cole\u2009\u00bb, ne faites pas irruption dans leur chambre pour les observer. Ils ne sont pas \u00e0 la maison en train de surfer sur le Net, ils sont \u00e0 l\u2019\u00e9cole et vous devez agir comme si leur chambre \u00e9tait situ\u00e9e dans une autre dimension.<\/p>\n<p>Vous devez \u00e9videmment exiger la m\u00eame chose lorsque vous travaillez. Il est tr\u00e8s facile d\u2019oublier que quelqu\u2019un qui travaille \u00e0 distance est tout aussi occup\u00e9 que s\u2019il \u00e9tait au bureau.<\/p>\n<h4>Travailler en famille<\/h4>\n<p>M\u00eame si la p\u00e9riode actuelle est difficile pour tous ceux qui sont malades, et que les cons\u00e9quences sur l\u2019\u00e9conomie pourraient \u00eatre consid\u00e9rables, le moment est id\u00e9al pour comprendre la valeur de notre communaut\u00e9 et de notre famille.<\/p>\n<p>Essayez de vous int\u00e9resser aux passe-temps de vos enfants. Non seulement cela pourrait \u00eatre divertissant, mais vous pourriez aussi en savoir davantage sur eux et sur les jeux qu\u2019ils aiment. Vous pouvez par ailleurs leur expliquer comment faire face aux <a href=\"https:\/\/www.le-vpn.com\/fr\/jeux-video\/\">comportements abusifs dans les jeux vid\u00e9o<\/a> ou comment identifier les aspects d\u2019internet qui sont s\u00fbrs pour eux et ceux qui ne le sont pas.<\/p>\n<h3>Conclusion<\/h3>\n<p>La pand\u00e9mie\u00a0Covid-19 ne sera peut-\u00eatre pas directement catastrophique pour vous ou vos proches, mais elle peut l\u2019\u00eatre pour d\u2019autres personnes. Sans compter qu\u2019il existe un risque de surcharge dans les h\u00f4pitaux, et que cela pourrait donc aussi affecter les personnes qui s\u2019y rendent pour d\u2019autres raisons. C\u2019est pourquoi il est indispensable que nous restions chez nous pendant les prochaines semaines.<\/p>\n<p>Et bien que des probl\u00e8mes techniques et de connexion puissent survenir, puisque tout le monde ou presque est connect\u00e9, avec des outils comme l\u2019application Le VPN, nous pouvons facilement les contourner.<\/p>\n<p>La seule chose \u00e0 laquelle vous devez alors penser est de prendre soin de vous et des autres, et de chercher \u00e0 rester aussi positif que possible. Et finalement, il se pourrait m\u00eame que nous en tirions tous quelque chose de b\u00e9n\u00e9fique.<\/p>\n[vc_row][vc_column]<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-536a04c9d416483\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div data-id=\"mpc_callout-626a04c9d414df6\" class=\"mpc-callout mpc-init mpc-callout--style_1 \"><div class=\"mpc-callout__icon-wrap mpc-icon--image\"><div class=\"mpc-callout__icon\"><i class=\"mpc-transition \"><img decoding=\"async\" class=\"\" src=\"https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2025\/09\/exclusive-deal.png\" width=\"100\" height=\"100\" alt=\"exclusive-deal\" title=\"exclusive-deal\" loading=\"lazy\"><\/i><\/div><\/div><div class=\"mpc-callout__content\"><h3 class=\"mpc-callout__heading mpc-typography--preset_1\">OFFRE EXCLUSIVE<\/h3><div data-id=\"mpc_divider-486a04c9d414ea0\" class=\"mpc-divider-wrap\"><div class=\"mpc-divider mpc-init mpc-align--center mpc-disable--left \"><div class=\"mpc-divider__line mpc-side--left\"><span><\/span><\/div><div class=\"mpc-divider__line mpc-side--right\"><span><\/span><\/div><\/div><\/div><div class=\"mpc-callout__description\"><p>LES 3 PREMI&Egrave;RES ANN&Eacute;ES &Agrave; 2,22 &euro;\/MOIS<\/p>\n<\/div><\/div><div class=\"mpc-callout__button\"><a href=\"https:\/\/www.le-vpn.com\/fr\/acheter-le-vpn\/\" title=\"\" data-id=\"mpc_button-516a04c9d414e69\" class=\"mpc-button mpc-init mpc-transition mpc-typography--preset_2 \"><div class=\"mpc-button__content mpc-effect-type--none mpc-effect-side--none\"><span class=\"mpc-button__title mpc-transition\">PROFITEZ EN<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1725366294400 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-446a04c9d4155d7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036137534\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>PAS DE JOURNAL<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1699541136156\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>100+ LOCALISATIONS<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-816a04c9d4158ea\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036153466\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>P2P autoris&eacute;<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036161279\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Facile &agrave; utiliser<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-86a04c9d415bba\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1622661737627\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:13px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Garantie de 30 Jours<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036177713\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Assistance amicale<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-186a04c9d415e84\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036185445\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Bitcoin accept&eacute;<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036194514\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Vitesse de l'&eacute;clair<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1701699917169 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-306a04c9d416bc9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\r\n<\/div>[\/vc_column][\/vc_row]<\/div>","protected":false},"excerpt":{"rendered":"<p>Les cours en ligne ont commenc\u00e9, et il est d\u00e9sormais clair que les \u00e9coles physiques n\u2019existent pas seulement pour \u00e9duquer les enfants, mais aussi pour pr\u00e9server la sant\u00e9 mentale des parents. Quoi qu\u2019il en soit, la quarantaine que nous devons endurer pendant cette crise du Covid-19 va poser quelques probl\u00e8mes, mais aussi apporter certains avantages.<\/p>\n","protected":false},"author":11,"featured_media":32651,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_metadesc":"\u00c9cole en Ligne : Pendant le confinement li\u00e9 au Covid-19, il ne faut pas seulement penser au virus, mais aussi \u00e0 notre sant\u00e9 mentale et num\u00e9rique, et \u00e0 celle de vos enfants.","footnotes":""},"categories":[833,3781],"tags":[],"yst_prominent_words":[7494,7493,7495,4544,7478,1224,7496,3787,4319,1078,2177,1582,1312,1725,1595,3139,7491,7492,2654,1565],"class_list":["post-32636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog_old","category-top-stories"],"_links":{"self":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/32636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/comments?post=32636"}],"version-history":[{"count":3,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/32636\/revisions"}],"predecessor-version":[{"id":32652,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/32636\/revisions\/32652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/media\/32651"}],"wp:attachment":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/media?parent=32636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/categories?post=32636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/tags?post=32636"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=32636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}