{"id":31562,"date":"2018-11-02T11:39:07","date_gmt":"2018-11-02T09:39:07","guid":{"rendered":"https:\/\/www.le-vpn.com\/fr\/?p=31562"},"modified":"2018-11-02T11:39:07","modified_gmt":"2018-11-02T09:39:07","slug":"pas-louper-octobre","status":"publish","type":"post","link":"https:\/\/www.le-vpn.com\/fr\/pas-louper-octobre\/","title":{"rendered":"Ce qu\u2019il ne fallait pas louper en octobre chez Le VPN"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>Chaque mois, Le VPN vous fait un petit r\u00e9sum\u00e9 de l\u2019actualit\u00e9 du r\u00e9seau, de la s\u00e9curit\u00e9 et des choses qui gravitent autour de la notion de VPN. C\u2019est un moyen efficace et rapide de se tenir constamment inform\u00e9 des nouvelles de notre petite sph\u00e8re sans trop y passer de temps\u00a0! N\u2019oubliez pas que chaque titre d\u2019article est cliquable afin d\u2019aller pouvoir lire le texte dans son enti\u00e8ret\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h2>A ne pas louper n\u00b01\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/que-peut-faire-un-vpn\/\">Que peut faire un VPN pour assurer votre cybers\u00e9curit\u00e9\u00a0?<\/a><\/h2>\n<p>Un r\u00e9capitulatif des origines des menaces, et des solutions que peut y apporter un VPN. L\u2019auteur \u00e9tablit ensuite une comparaison entre un VPN et d\u2019autres solutions d\u2019anonymisation comme TOR ou les proxy. Enfin l\u2019article \u00e9tablit une liste des points cl\u00e9s \u00e0 prendre en compte avant de s\u2019abonner \u00e0 un VPN, et rappelle quels sont les usages qui peuvent en \u00eatre fait. Cet article condense \u00e0 lui seul une grande partie des questions (et y donne des r\u00e9ponses) que pourrait se poser un novice ayant envie de se procurer une solution de s\u00e9curit\u00e9 de ce type.<\/p>\n<h2>A ne pas louper n\u00b02\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/red-pill-ctf\/\">Le VPN sponsorise la comp\u00e9tition de hacking RED PILL CTF\u00a0!<\/a><\/h2>\n<p>Le VPN sponsorise une comp\u00e9tition de hacking\u00a0! En effet, le club kr[HACK]en, organise une comp\u00e9tition de ce type en parall\u00e8le de la CSAW\u201918 qui se tiendra du 8 au 11 novembre \u00e0 Valence. Cette comp\u00e9tition, la RED PILL CTF, est un bon moyen de sensibiliser les \u00e9tudiants (et les autres\u00a0!) aux probl\u00e9matiques actuelles de la cyber s\u00e9curit\u00e9, et de d\u00e9montrer l\u2019importance d\u2019adopter certaines protections. Tous les participants de la CSAW repartiront avec un an d\u2019abonnement gratuit \u00e0 nos services\u00a0!<\/p>\n<h2>A ne pas louper n\u00b03\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/securite-mobile-applications-android\/\">S\u00e9curit\u00e9 mobile, les meilleures applications Android en 2018<\/a><\/h2>\n<p>Cette article pr\u00e9sente les menaces qui peuvent planer sur nos smartphones et dresse une liste des logiciels de s\u00e9curit\u00e9 qui peuvent aider \u00e0 s\u2019en pr\u00e9munir. Enfin, l\u2019auteur \u00e9tablit une liste des applications permettant d\u2019obtenir la meilleure protection sur un appareil Android.<\/p>\n<h2>A ne pas louper n\u00b04\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/google-dragonfly\/\">Le PDG de Google s\u2019exprime sur le projet Dragonfly<\/a><\/h2>\n<p>Le projet Dragonfly, c\u2019est le moteur de recherche Google, revu et corrig\u00e9 pour le march\u00e9 chinois. C\u2019est-\u00e0-dire, une version censur\u00e9e de Google qui r\u00e9pond aux valeurs que pr\u00f4nent le gouvernement chinois. Le march\u00e9 \u00e0 prendre est immense, mais les critiques envers cette volont\u00e9 du g\u00e9ant californien le sont aussi\u00a0!<\/p>\n<h2>A ne pas louper n\u00b05\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/solutions-naviguer-anonymement\/\">Les 10 meilleures solutions pour naviguer anonymement<\/a><\/h2>\n<p>Ce texte dresse un portrait des acteurs qui cherchent \u00e0 obtenir vos donn\u00e9es, puis vous propose une liste d\u00e9taill\u00e9e des moyens techniques pouvant permettre de conserver un certain anonymat sur Internet<\/p>\n<h2>A ne pas louper n\u00b06\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/faille-whatsapp\/\">Une faille importante de WhatsApp a \u00e9t\u00e9 combl\u00e9e<\/a><\/h2>\n<p>Une faille qui permettait de faire planter WhatsApp \u00e0 distance, et donc potentiellement de profiter d\u2019une porte d\u2019entr\u00e9e comme d\u2019un acc\u00e8s \u00e0 la m\u00e9moire (?), a \u00e9t\u00e9 combl\u00e9e ce mois-ci par l\u2019entreprise. La d\u00e9couverte de ce genre de faille est tr\u00e8s commune en ce moment, cet article vous rappelle qu\u2019utiliser Le VPN est un bon moyen de se pr\u00e9munir de beaucoup de menaces.<\/p>\n<h2>A ne pas louper n\u00b07\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/eviter-cyberharcelement\/\">Comment \u00e9viter le cyber harc\u00e8lement\u00a0?<\/a><\/h2>\n<p>&nbsp;<\/p>\n<p>Un rappel de ce qu\u2019est le cyber harc\u00e8lement, de l\u00e0 o\u00f9 il est le plus commun et des moyens de s\u2019en prot\u00e9ger. Le cyber harc\u00e8lement est un fl\u00e9au qui touche tout le monde, mais les jeunes, par l\u2019interm\u00e9diaire des r\u00e9seaux sociaux sont bien entendu les plus touch\u00e9s et les plus fragiles.<\/p>\n<h2>A ne pas louper n\u00b08\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/fin-google\/\">Google annonce la fermeture de son r\u00e9seau social Google +<\/a><\/h2>\n<p>La d\u00e9couverte d\u2019une faille aura \u00e9t\u00e9 la goutte d\u2019eau\u00a0! Google annonce suite \u00e0 cette trouvaille qu\u2019il fermera d\u00e9finitivement son r\u00e9seau social dans quelque mois. Google + n\u2019a jamais r\u00e9ellement trouv\u00e9 son public, et si tous ceux qui disposent d\u2019une adresse Gmail ont automatiquement un compte sur G+, ils sont bien peu \u00e0 utiliser le r\u00e9seau.<\/p>\n<h2>A ne pas louper n\u00b09\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/mois-cyber-securite\/\">Octobre c\u2019est le mois de la cybers\u00e9curit\u00e9<\/a><\/h2>\n<p>Le mois d\u2019octobre est celui de la Cyber Security Awarness\u00a0! Le mois de l\u2019information et de la sensibilisation \u00e0 la cyber s\u00e9curit\u00e9. Chez Le VPN, nous pensons que de telles initiatives sont primordiales dans un monde o\u00f9 le recours au r\u00e9seau internet est devenu in\u00e9vitable. Durant ce mois, beaucoup d\u2019acteurs ont multipliaient les conf\u00e9rences, et les diff\u00e9rentes initiatives afin de sensibiliser le plus de monde possible aux menaces qui existent dans notre monde num\u00e9rique.<\/p>\n<h2>A ne pas louper n\u00b010\u00a0: <a href=\"https:\/\/www.le-vpn.com\/fr\/chiffrement-des-donnees-7-choses-a-savoir\/\">Comment fonctionne le chiffrement des donn\u00e9es\u00a0?<\/a><\/h2>\n<p>Qu\u2019est-ce que le chiffrement\u00a0? Pourquoi devons-nous chiffrer certaines donn\u00e9es\u00a0? Que se passerait-il si toutes vos donn\u00e9es circulaient en clair\u00a0? Cette article vous propose 7 faits int\u00e9ressants et parfois surprenant autour de la th\u00e9matique du chiffrement. En savoir le plus possible, c\u2019est \u00eatre capable de garantir sa s\u00e9curit\u00e9 en ligne.<\/p>\n[vc_row][vc_column]<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-436a04e2fac52e3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div data-id=\"mpc_callout-36a04e2fac358b\" class=\"mpc-callout mpc-init mpc-callout--style_1 \"><div class=\"mpc-callout__icon-wrap mpc-icon--image\"><div class=\"mpc-callout__icon\"><i class=\"mpc-transition \"><img decoding=\"async\" class=\"\" src=\"https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2025\/09\/exclusive-deal.png\" width=\"100\" height=\"100\" alt=\"exclusive-deal\" title=\"exclusive-deal\" loading=\"lazy\"><\/i><\/div><\/div><div class=\"mpc-callout__content\"><h3 class=\"mpc-callout__heading mpc-typography--preset_1\">OFFRE EXCLUSIVE<\/h3><div data-id=\"mpc_divider-936a04e2fac3631\" class=\"mpc-divider-wrap\"><div class=\"mpc-divider mpc-init mpc-align--center mpc-disable--left \"><div class=\"mpc-divider__line mpc-side--left\"><span><\/span><\/div><div class=\"mpc-divider__line mpc-side--right\"><span><\/span><\/div><\/div><\/div><div class=\"mpc-callout__description\"><p>LES 3 PREMI&Egrave;RES ANN&Eacute;ES &Agrave; 2,22 &euro;\/MOIS<\/p>\n<\/div><\/div><div class=\"mpc-callout__button\"><a href=\"https:\/\/www.le-vpn.com\/fr\/acheter-le-vpn\/\" title=\"\" data-id=\"mpc_button-976a04e2fac35f4\" class=\"mpc-button mpc-init mpc-transition mpc-typography--preset_2 \"><div class=\"mpc-button__content mpc-effect-type--none mpc-effect-side--none\"><span class=\"mpc-button__title mpc-transition\">PROFITEZ EN<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1725366294400 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-856a04e2fac3fce\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036137534\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>PAS DE JOURNAL<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1699541136156\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>100+ LOCALISATIONS<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-746a04e2fac4452\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036153466\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>P2P autoris&eacute;<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036161279\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Facile &agrave; utiliser<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-336a04e2fac47c9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1622661737627\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:13px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Garantie de 30 Jours<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036177713\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Assistance amicale<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-566a04e2fac4b5d\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036185445\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Bitcoin accept&eacute;<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036194514\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Vitesse de l'&eacute;clair<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1701699917169 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-156a04e2fac5b81\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\r\n<\/div>[\/vc_column][\/vc_row]<\/div>","protected":false},"excerpt":{"rendered":"<p>Chaque mois, Le VPN vous fait un petit r\u00e9sum\u00e9 de l\u2019actualit\u00e9 du r\u00e9seau, de la s\u00e9curit\u00e9 et des choses qui gravitent autour de la notion de VPN. C\u2019est un moyen efficace et rapide de se tenir constamment inform\u00e9 des nouvelles de notre petite sph\u00e8re sans trop y passer de temps\u00a0! N\u2019oubliez pas que chaque titre<\/p>\n","protected":false},"author":16,"featured_media":31563,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_metadesc":"Ce qu'il ne fallait pas louper en octobre chez Le VPN, un r\u00e9sum\u00e9 des articles de cyber s\u00e9curit\u00e9 parus durant le mois sur notre blog !","footnotes":""},"categories":[833,3781],"tags":[268,6401,4053,6372,6419,309,6418],"yst_prominent_words":[6417,6412,2046,6411,2036,6413,2052,6414,6415,5858,2043,6389,6091,6390,6388,1594,2000,1116,1565,6416],"class_list":["post-31562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog_old","category-top-stories","tag-chine","tag-csaw","tag-cyber-securite","tag-dragonfly","tag-g","tag-google-2","tag-pas-louper-octobre"],"_links":{"self":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/31562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/comments?post=31562"}],"version-history":[{"count":1,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/31562\/revisions"}],"predecessor-version":[{"id":31564,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/31562\/revisions\/31564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/media\/31563"}],"wp:attachment":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/media?parent=31562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/categories?post=31562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/tags?post=31562"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=31562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}