{"id":30748,"date":"2018-03-09T12:23:51","date_gmt":"2018-03-09T10:23:51","guid":{"rendered":"https:\/\/www.le-vpn.com\/fr\/?p=30748"},"modified":"2020-07-16T20:48:51","modified_gmt":"2020-07-16T18:48:51","slug":"adresses-ip-a-cote-des-commentaires","status":"publish","type":"post","link":"https:\/\/www.le-vpn.com\/fr\/adresses-ip-a-cote-des-commentaires\/","title":{"rendered":"Arrivera-t-on \u00e0 la publication des adresses IP \u00e0 c\u00f4t\u00e9 des commentaires ?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>Il y a une news ayant attrait \u00e0 l\u2019informatique, et plus particuli\u00e8rement \u00e0 l\u2019anonymat sur Internet, qui a beaucoup fait causer cette semaine, c\u2019est celle relative \u00e0 la publication de l\u2019adresse IP des auteurs de commentaires sur les sites web.<\/p>\n<p>Mardi 27 f\u00e9vrier, la d\u00e9put\u00e9e Isabelle Rauch a transmis une question \u00e9crite au secr\u00e9taire d\u2019Etat au Num\u00e9rique, afin de lui demander, s\u2019il \u00e9tait envisageable, que l\u2019adresse IP soit publi\u00e9e, en m\u00eame temps qu\u2019un commentaire. Ceci afin de lutter contre les commentaires malveillants, qui fleurissent un peu partout sur le r\u00e9seau.<\/p>\n<h2>Les faux avis<\/h2>\n<p>Quand Mme Rauch parle d\u2019avis malveillants, elle fait r\u00e9f\u00e9rence, principalement, aux faux avis publi\u00e9s sur certains sites web, comme ceux donnant des avis sur la restauration, l\u2019h\u00f4tellerie, les voyages\u2026 Il est important de comprendre que, sur ce type de sites, beaucoup d\u2019avis sont \u00e9crits par la concurrence, ou, dict\u00e9s par elle \u00e0 des entreprises sp\u00e9cialis\u00e9es dans la r\u00e9daction de ce type d\u2019avis.<\/p>\n<p>Et pour responsabiliser les r\u00e9dacteurs de ces textes, voire supprimer ce type de commentaires, l\u2019id\u00e9e de la d\u00e9put\u00e9e, est que l\u2019adresse IP de celui qui laisse son avis, soit publi\u00e9e, en m\u00eame temps que le commentaire. L\u2019adresse IP, pour m\u00e9moire, est l\u2019adresse informatique qui permet d\u2019identifier, de mani\u00e8re unique, votre routeur (pour faire simple), et donc, son propri\u00e9taire, sa zone g\u00e9ographique, son FAI\u2026<\/p>\n<ol>\n<li>Mounir Mahjoubi, le secr\u00e9taire d\u2019\u00e9tat charg\u00e9 du num\u00e9rique, dispose de deux mois pour apporter une r\u00e9ponse \u00e0 l\u2019interrogation de Mme Rauch. Mais les diff\u00e9rents acteurs du secteur ont d\u00e9j\u00e0 une petite id\u00e9e de ce qu\u2019elle sera.<\/li>\n<\/ol>\n<h2>Impossibilit\u00e9 et moyens de contournement<\/h2>\n<p>Pour commencer, la CNIL consid\u00e8re que l\u2019adresse IP est une information relevant du domaine des donn\u00e9es personnelles, il serait donc tr\u00e8s difficile qu\u2019elle soit publi\u00e9e aux yeux de tous. Ensuite, et c\u2019est l\u00e0 que <a href=\"https:\/\/www.le-vpn.com\/fr\/\">Le VPN<\/a> intervient, proposer ce genre de proc\u00e9dure, d\u00e9montre que certains m\u00e9connaissent, encore bien trop, certains aspects de la technicit\u00e9 d\u2019internet.<\/p>\n<p>Il serait tr\u00e8s facile, si une telle mesure venait \u00e0 \u00eatre mise en place, de la contourner, et d\u2019afficher une adresse IP diff\u00e9rente de la sienne. En utilisant un VPN ou un <a href=\"https:\/\/www.le-vpn.com\/fr\/quest-ce-quun-proxy\/\">proxy<\/a> par exemple. Si tant est que la Cnil aurait autoris\u00e9 cette publication\u2026 Ces solutions de contournement, paraissent tellement \u00e9videntes \u00e0 ceux qui sont au fait de ce qui se fait dans le domaine de la s\u00e9curisation, que Mme la d\u00e9put\u00e9e a \u00e9t\u00e9 la ris\u00e9e des diff\u00e9rents r\u00e9seaux sociaux, depuis cette annonce. Car l\u2019objet de cette demande est \u00e0 l\u2019encontre m\u00eame du principe intrins\u00e8que d\u2019un Vpn. En plus de crypter vos donn\u00e9es, entre un point A et un point B, en faisant intervenir un serveur tiers, qui tiens le r\u00f4le d\u2019interm\u00e9diaire, le service Vpn changera votre IP publique, puisque celle-ci sera celle de son serveur.<\/p>\n<p>Cette question de la d\u00e9put\u00e9e Rauch, n\u2019obtiendra pas de r\u00e9ponse positive, puisqu\u2019il n\u2019y a pas de r\u00e9ponse compatible avec les possibilit\u00e9s technologiques actuelles. Mais si un jour, de telles contraintes devaient \u00eatre impos\u00e9es aux internautes, vous vous rappellerez, qu\u2019aujourd\u2019hui Le VPN vous en avez parl\u00e9, et que <a href=\"https:\/\/www.le-vpn.com\/fr\/comment-masquer-mon-adresse-ip\/\">nous proposons la technologie<\/a> permettant de ne pas se soumettre \u00e0 de tels dict\u00e2tes liberticides et non respectueux de votre vie personnelle.<\/p>\n[vc_row][vc_column]<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-386a04cbf14950f\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div data-id=\"mpc_callout-146a04cbf1455cd\" class=\"mpc-callout mpc-init mpc-callout--style_1 \"><div class=\"mpc-callout__icon-wrap mpc-icon--image\"><div class=\"mpc-callout__icon\"><i class=\"mpc-transition \"><img decoding=\"async\" class=\"\" src=\"https:\/\/www.le-vpn.com\/fr\/wp-content\/uploads\/2025\/09\/exclusive-deal.png\" width=\"100\" height=\"100\" alt=\"exclusive-deal\" title=\"exclusive-deal\" loading=\"lazy\"><\/i><\/div><\/div><div class=\"mpc-callout__content\"><h3 class=\"mpc-callout__heading mpc-typography--preset_1\">OFFRE EXCLUSIVE<\/h3><div data-id=\"mpc_divider-446a04cbf1456a9\" class=\"mpc-divider-wrap\"><div class=\"mpc-divider mpc-init mpc-align--center mpc-disable--left \"><div class=\"mpc-divider__line mpc-side--left\"><span><\/span><\/div><div class=\"mpc-divider__line mpc-side--right\"><span><\/span><\/div><\/div><\/div><div class=\"mpc-callout__description\"><p>LES 3 PREMI&Egrave;RES ANN&Eacute;ES &Agrave; 2,22 &euro;\/MOIS<\/p>\n<\/div><\/div><div class=\"mpc-callout__button\"><a href=\"https:\/\/www.le-vpn.com\/fr\/acheter-le-vpn\/\" title=\"\" data-id=\"mpc_button-356a04cbf145652\" class=\"mpc-button mpc-init mpc-transition mpc-typography--preset_2 \"><div class=\"mpc-button__content mpc-effect-type--none mpc-effect-side--none\"><span class=\"mpc-button__title mpc-transition\">PROFITEZ EN<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1725366294400 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-476a04cbf14618a\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036137534\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>PAS DE JOURNAL<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1699541136156\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>100+ LOCALISATIONS<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-806a04cbf146630\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036153466\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>P2P autoris&eacute;<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036161279\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Facile &agrave; utiliser<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-756a04cbf146a5b\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1622661737627\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:13px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Garantie de 30 Jours<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036177713\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Assistance amicale<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-956a04cbf146e82\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036185445\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Bitcoin accept&eacute;<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619036194514\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:14px;color:#444;text-transform: uppercase;margin-left:20px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>Vitesse de l'&eacute;clair<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1701699917169 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-216a04cbf14abf5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\r\n<\/div>[\/vc_column][\/vc_row]<\/div>","protected":false},"excerpt":{"rendered":"<p>Il y a une news ayant attrait \u00e0 l\u2019informatique, et plus particuli\u00e8rement \u00e0 l\u2019anonymat sur Internet, qui a beaucoup fait causer cette semaine, c\u2019est celle relative \u00e0 la publication de l\u2019adresse IP des auteurs de commentaires sur les sites web. Mardi 27 f\u00e9vrier, la d\u00e9put\u00e9e Isabelle Rauch a transmis une question \u00e9crite au secr\u00e9taire d\u2019Etat<\/p>\n","protected":false},"author":16,"featured_media":30749,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_metadesc":"Que ce passe-t-il quand une d\u00e9put\u00e9e a l\u2019id\u00e9e de publier les adresses IP \u00e0 c\u00f4t\u00e9 des commentaires ? Et bien beaucoup de monde rigole\u2026","footnotes":""},"categories":[833,3781],"tags":[4055,260,325,422,281],"yst_prominent_words":[4681,1738,4569,5195,5194,5191,1746,3144,5104,5192,5197,3669,5193,5196,5198,1593,1118,3152,1565,1729],"class_list":["post-30748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog_old","category-top-stories","tag-anonymat","tag-anonymat-sur-internet","tag-cacher-son-adresse-ip","tag-changer-son-adresse-ip","tag-masquer-son-adresse-ip"],"_links":{"self":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/30748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/comments?post=30748"}],"version-history":[{"count":1,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/30748\/revisions"}],"predecessor-version":[{"id":30750,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/posts\/30748\/revisions\/30750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/media\/30749"}],"wp:attachment":[{"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/media?parent=30748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/categories?post=30748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/tags?post=30748"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.le-vpn.com\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=30748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}