{"id":15484,"date":"2021-11-10T19:12:33","date_gmt":"2021-11-10T19:12:33","guid":{"rendered":"https:\/\/www.le-vpn.com\/es\/?p=15484"},"modified":"2021-11-10T19:14:36","modified_gmt":"2021-11-10T19:14:36","slug":"le-vpn-cumple-11","status":"publish","type":"post","link":"https:\/\/www.le-vpn.com\/es\/le-vpn-cumple-11\/","title":{"rendered":"Le VPN Cumple 11 a\u00f1os: La Historia hasta Ahora"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>\u00bfRecuerdas ese gran evento que sucedi\u00f3 en 2010? No, no estoy hablando de que Apple haya lanzado el primer iPad, ni de que Dubai haya inaugurado el edificio m\u00e1s alto del mundo. Estoy hablando del<strong> nacimiento de la VPN en la que conf\u00edan millones de usuarios: Le VPN.<\/strong><\/p>\n<p>Le VPN est\u00e1 celebrando 11 a\u00f1os brindando a los usuarios una internet m\u00e1s segura, sin restricciones y m\u00e1s privada, y estoy investigando cu\u00e1nto ha logrado la compa\u00f1\u00eda en ese tiempo. MUCHO ha cambiado en los \u00faltimos 11 a\u00f1os, pero los <a href=\"https:\/\/www.le-vpn.com\/es\/quienes-somos\/\"><strong>valores fundamentales<\/strong><\/a> de la marca no han cambiado ni un \u00e1pice.<\/p>\n<p>Analicemos en profundidad d\u00f3nde comenz\u00f3 Le VPN, por qu\u00e9 los usuarios recurren a ella para proteger su privacidad y c\u00f3mo es el futuro de la empresa.<\/p>\n<h2>Donde Empez\u00f3 Todo<\/h2>\n<p>El 10 de noviembre de 2010, los fundadores de Le VPN formaron un equipo compuesto por expertos en ciberseguridad y profesionales empresariales y se unieron para crear <strong>la primera soluci\u00f3n VPN personal de Francia<\/strong>.<\/p>\n<p>Como no hab\u00eda estado presente durante las etapas de creaci\u00f3n de Le VPN, le pregunt\u00e9 al fundador Konstantin Votinov <strong>qu\u00e9 hizo que \u00e9l y los otros fundadores decidieran entrar en el negocio de las VPN<\/strong>. Explic\u00f3:<\/p>\n<blockquote><p><em>&#8220;Le VPN comenz\u00f3 como resultado de una extensa investigaci\u00f3n contra el ciberdelito. Se nos ocurri\u00f3 una idea para llevar la privacidad y la seguridad del mundo subterr\u00e1neo a todos los usuarios de internet.<\/em><\/p>\n<p><em>En 2010, el paradigma de la privacidad comenz\u00f3 a cambiar. Los pa\u00edses y las corporaciones comenzaron a involucrarse m\u00e1s en la regulaci\u00f3n de la tierra libre de internet. Algunas libertades se negociaron para satisfacer la sed de dinero de las corporaciones; otras, para proporcionar m\u00e1s poder al estado&#8221;.<\/em><\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-15489\" src=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Username-password-1200x628-1.jpg\" alt=\"Le VPN Cumple 11 a\u00f1os: La Historia hasta Ahora. | Le VPN\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Username-password-1200x628-1.jpg 1200w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Username-password-1200x628-1-300x157.jpg 300w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Username-password-1200x628-1-1024x536.jpg 1024w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Username-password-1200x628-1-768x402.jpg 768w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Username-password-1200x628-1-500x262.jpg 500w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Continu\u00f3:<\/p>\n<blockquote><p><em>&#8220;En ese momento, la poblaci\u00f3n de internet comenz\u00f3 a sentir los primeros toques sucios de los reguladores. Le VPN fue nuestra respuesta a eso. Quer\u00edamos proporcionar una herramienta para proteger a los usuarios y educarlos con un estilo de vida seguro con respecto a sus datos.<\/em><\/p>\n<p><em>Desde entonces, hemos intervenido en m\u00faltiples crisis de censura para brindar a la poblaci\u00f3n oprimida acceso a una de las necesidades b\u00e1sicas del siglo XXI: el acceso a la informaci\u00f3n. Durante los \u00faltimos 11 a\u00f1os, hemos mantenido nuestra lucha por la libertad en internet\u201d.<\/em><\/p><\/blockquote>\n<p>Elegir un nombre de marca no es una tarea f\u00e1cil, especialmente cuando se convertir\u00eda en un nombre reconocido a escala mundial. Decid\u00ed profundizar a\u00fan m\u00e1s para entender de d\u00f3nde ven\u00eda el nombre Le VPN.<\/p>\n<p>Cuando le pregunt\u00e9 a Konstantin &#8220;<strong>\u00bf<\/strong><strong>Por qu\u00e9 Le VPN?<\/strong>&#8220;, afirm\u00f3:<\/p>\n<blockquote><p><em>&#8220;Le VPN se cre\u00f3 en Francia y en su primer a\u00f1o fue el \u00fanico servicio en el mercado franc\u00e9s. Como \u00e9ramos los \u00fanicos en ese lugar y momento, tomamos el nombre de Le VPN, o LA VPN cuando el art\u00edculo franc\u00e9s &#8220;Le&#8221; se traduce al espa\u00f1ol. Pensamos que si somos los \u00fanicos aqu\u00ed, \u00bfpor qu\u00e9 no ser LA \u00fanica VPN? Y luego ese nombre qued\u00f3&#8221;.<\/em><\/p><\/blockquote>\n<h2>El Camino Al \u00c9xito<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-15490\" src=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/The-road-to-success-1200x628-1.jpg\" alt=\"Le VPN Cumple 11 a\u00f1os: La Historia hasta Ahora. | Le VPN\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/The-road-to-success-1200x628-1.jpg 1200w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/The-road-to-success-1200x628-1-300x157.jpg 300w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/The-road-to-success-1200x628-1-1024x536.jpg 1024w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/The-road-to-success-1200x628-1-768x402.jpg 768w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/The-road-to-success-1200x628-1-500x262.jpg 500w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>El primer concepto de PPTP (Protocolo de T\u00fanel Punto a Punto) aterriz\u00f3 en 1996 gracias a un ingeniero de Microsoft llamado Gurdeep Singh Pall. Despu\u00e9s del milenio (y evitando el llamado &#8220;error del milenio&#8221;) y el surgimiento de velocidades de banda ancha m\u00e1s r\u00e1pidas, las VPN comenzaron a aparecer en todos los rincones del mundo.<\/p>\n<p>Cuando Le VPN se uni\u00f3 como actor de ciberseguridad en 2010, ya hab\u00eda mucho ruido y proveedores establecidos compitiendo por el puesto como el proveedor de VPN n\u00famero 1.<\/p>\n<p>\u00bfRecuerdas el viejo dicho, &#8220;puedes aprender de tus errores&#8221;? Ese mismo principio se aplica tambi\u00e9n a las marcas globales de VPN. Los desaf\u00edos en los negocios deber\u00edan venir con una etiqueta de advertencia (algo as\u00ed como \u201cesto no va a ser f\u00e1cil\u201d) porque es imposible hacer todo bien en las etapas iniciales del negocio.<\/p>\n<p>Entonces, \u00bfqu\u00e9 signific\u00f3 eso para Le VPN? Quer\u00eda comprender algunos de los obst\u00e1culos que la empresa ha tenido que superar antes de cumplir 11 a\u00f1os, as\u00ed que, le hice la pregunta a Ksenia Votinova, cofundadora de la empresa en 2012.<\/p>\n<p><strong>\u00bfA qu\u00e9 desaf\u00edos se ha enfrentado Le VPN (si existieron) a lo largo de los a\u00f1os?<\/strong> Ella respondi\u00f3 para decirme que,<\/p>\n<blockquote><p><em>\u201cLas grandes plataformas de transmisi\u00f3n como Netflix y Disney + que bloquean los servicios VPN son un gran desaf\u00edo, y tienen grandes equipos dedicados a esa tarea, lo que lo hace muy dif\u00edcil y, a veces, imposible para nosotros.<\/em><\/p>\n<p><em>Tuvimos que dejar de jugar a este juego de \u2018Las escondidas\u2019 con Netflix y sus rivales para concentrarnos en brindar el mejor servicio VPN seguro y privado posible, que es el n\u00facleo de nuestro negocio. Tambi\u00e9n existen desaf\u00edos a nivel de pa\u00eds a medida que comenzamos a ver que m\u00e1s regiones aumentan su censura y bloquean a los proveedores de VPN, por ejemplo, en Rusia, uno de nuestros mercados clave.<\/em><\/p>\n<p><em>Es posible que esta tendencia se traslade a otras geograf\u00edas que adoptar\u00e1n la pol\u00edtica de China, y haremos todo lo posible para tratar de superar esos l\u00edmites siempre que sea posible y llevar la libertad de internet a todos&#8221;.<\/em><\/p><\/blockquote>\n<p>Romain Malburet, Jefe de Soporte al Cliente, brind\u00f3 su perspectiva:<\/p>\n<blockquote><p><em>&#8220;Enfrentamos desaf\u00edos en algunos pa\u00edses donde internet est\u00e1 censurada y las VPN est\u00e1n prohibidas, pero por ahora, casi siempre encontramos una soluci\u00f3n para los usuarios de la VPN&#8221;.<\/em><\/p><\/blockquote>\n<p>Continu\u00f3:<\/p>\n<blockquote><p><em>&#8220;La generalizaci\u00f3n del DNS encriptado podr\u00eda ser un nuevo desaf\u00edo en los pr\u00f3ximos meses, as\u00ed como la trivializaci\u00f3n de ciertos bloqueos, como vimos recientemente para un portal escolar en l\u00ednea en Arabia Saudita. Afortunadamente, estamos listos para estos nuevos desaf\u00edos a fin de poder brindar una experiencia mejor y m\u00e1s segura a nuestros clientes&#8221;.<\/em><\/p><\/blockquote>\n<p>Algunos dir\u00edan que ning\u00fan negocio es igual que cuando comenz\u00f3. La tecnolog\u00eda cambia, las leyes se actualizan y las restricciones de internet se vuelven m\u00e1s sofisticadas, por lo que una marca en el espacio de la ciberseguridad debe evolucionar para mantenerse a la vanguardia.<\/p>\n<p>El desaf\u00edo, sin embargo, es c\u00f3mo adaptarse a estos cambios sin afectar lo que representa Le VPN. Le hice la pregunta a Ksenia: &#8220;\u00bf<strong>Qu\u00e9 cambios han sido necesarios para evitar que Le VPN se quede atr\u00e1s de sus competidores?<\/strong>&#8221; Ella advirti\u00f3 que,<\/p>\n<blockquote><p><em>\u201ccuando comenzamos hace 11 a\u00f1os, la raz\u00f3n principal para usar una VPN era para P2P y servicios de intercambio de archivos como BitTorrent y eMule, que estaban en la cima de su popularidad en ese momento. \u00a1Incluso yo ten\u00eda uno!&#8221;<\/em><\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-15491\" src=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Streaming-movies-1200x628-1.jpg\" alt=\"Le VPN Cumple 11 a\u00f1os: La Historia hasta Ahora. | Le VPN\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Streaming-movies-1200x628-1.jpg 1200w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Streaming-movies-1200x628-1-300x157.jpg 300w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Streaming-movies-1200x628-1-1024x536.jpg 1024w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Streaming-movies-1200x628-1-768x402.jpg 768w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Streaming-movies-1200x628-1-500x262.jpg 500w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Ksenia continu\u00f3:<\/p>\n<blockquote><p><em>&#8220;Esos tiempos ya pasaron, ya que la descarga de pel\u00edculas es reemplazada por pel\u00edculas en tiempo real, y Netflix y otras plataformas han transformado la forma en que vemos la televisi\u00f3n. El entretenimiento y el acceso a los cat\u00e1logos mundiales de medios en l\u00ednea siguen siendo una gran tendencia, y seg\u00fan la investigaci\u00f3n an\u00f3nima que llevamos a cabo preguntando a los usuarios de Le VPN, sigue siendo la raz\u00f3n n\u00famero uno por la que nuestros usuarios utilizan una VPN.<\/em><\/p>\n<p><em>La tendencia de privacidad y seguridad en l\u00ednea se est\u00e1 recuperando justo detr\u00e1s del entretenimiento, especialmente para aquellos que se conectan desde cafeter\u00edas y lugares de trabajo remotos. Esta tendencia realmente ha crecido en 2020\/2021 durante la crisis del COVID-19, ya que todo el mundo tuvo que adaptarse al trabajo remoto y VPN se convirti\u00f3 en una necesidad en muchos escenarios\u201d.<\/em><\/p><\/blockquote>\n<h2>La Bienvenida a las Mujeres al Mundo de las VPN<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-15492\" src=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Women-in-tech-1200x628-1.jpg\" alt=\"Le VPN Cumple 11 a\u00f1os: La Historia hasta Ahora. | Le VPN\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Women-in-tech-1200x628-1.jpg 1200w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Women-in-tech-1200x628-1-300x157.jpg 300w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Women-in-tech-1200x628-1-1024x536.jpg 1024w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Women-in-tech-1200x628-1-768x402.jpg 768w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Women-in-tech-1200x628-1-500x262.jpg 500w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>No es ning\u00fan secreto que el mundo de las VPN estaba dominado por una base de usuarios masculinos cuando las VPN comenzaron a implementarse a principios de la d\u00e9cada de 2000, pero eso ha cambiado significativamente durante la \u00faltima d\u00e9cada.<\/p>\n<p>Claro, las VPN fueron una excelente manera de encriptar su tr\u00e1fico de internet para ocultar su actividad en l\u00ednea, pero a medida que las VPN han evolucionado, los casos de uso igualan la base de usuarios con <strong>m\u00e1s uso de VPN en la tecnolog\u00eda por parte de las mujeres<\/strong>.<\/p>\n<p>Las mujeres no solo usan VPN hoy en d\u00eda para desbloquear restricciones geogr\u00e1ficas o para evitar que los ISP limiten su conexi\u00f3n. Est\u00e1n eligiendo marcas como Le VPN para evitar el acoso cibern\u00e9tico a trav\u00e9s del correo electr\u00f3nico, las redes sociales y m\u00e1s al anonimizar su identidad en l\u00ednea. En \u00faltima instancia, esto hace que internet sea un lugar m\u00e1s seguro para todos, independientemente del g\u00e9nero.<\/p>\n<p>Ten\u00eda sentido obtener la perspectiva de una mujer, as\u00ed que le pregunt\u00e9 c\u00f3mo ha evolucionado la marca y <strong>c\u00f3mo es una mujer que trabaja en la industria de las VPN<\/strong>.<\/p>\n<p>Ella respondi\u00f3 para decirme que,<\/p>\n<blockquote><p><em>&#8220;Es cierto que en los eventos de ciberseguridad, generalmente me encuentro como la \u00fanica mujer en la sala, pero creo que las cosas ya est\u00e1n cambiando. La ley GDPR en Europa y leyes similares en otros pa\u00edses crearon m\u00e1s conciencia sobre la privacidad digital y la protecci\u00f3n de sus datos en l\u00ednea, y ese reclamo de privacidad no tiene g\u00e9nero. Tambi\u00e9n estoy emocionada de ver a m\u00e1s y m\u00e1s mujeres usando la aplicaci\u00f3n de Le VPN, y espero que esta tendencia siga creciendo&#8221;.<\/em><\/p><\/blockquote>\n<h2>Planes Para el Futuro<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-15493\" src=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Plans-for-the-future-1200x628-1.jpg\" alt=\"Le VPN Cumple 11 a\u00f1os: La Historia hasta Ahora. | Le VPN\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Plans-for-the-future-1200x628-1.jpg 1200w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Plans-for-the-future-1200x628-1-300x157.jpg 300w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Plans-for-the-future-1200x628-1-1024x536.jpg 1024w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Plans-for-the-future-1200x628-1-768x402.jpg 768w, https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2021\/11\/Plans-for-the-future-1200x628-1-500x262.jpg 500w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Como alguien que ha probado la aplicaci\u00f3n de Le VPN, disfruto cada momento. Como gran fan\u00e1tico de las pel\u00edculas y la televisi\u00f3n en el Reino Unido, no hay nada mejor que acurrucarme con mi familia en estas fr\u00edas noches con una nueva serie o pel\u00edcula que a\u00fan no hemos visto.<\/p>\n<p><strong>\u00bfQu\u00e9 la hace mejor, preguntas?<\/strong> Las bibliotecas de transmisi\u00f3n de medios en el Reino Unido no son tan vastas como en otras partes del mundo. Afortunadamente, Le VPN abre cat\u00e1logos de todo el mundo: \u00a1es como un boleto dorado para los mejores cat\u00e1logos de pel\u00edculas del mundo!<\/p>\n<p>En fin, estoy divagando, ya est\u00e1 bien de lo que me gusta de Le VPN, m\u00e1s sobre lo que est\u00e1 por venir. \u00a1Me prepar\u00e9 con una \u00faltima pregunta para Ksenia para que pudiera volver al trabajo!<\/p>\n<p>Le pregunt\u00e9 a <strong>d\u00f3nde cree que se dirige Le VPN en el futuro<\/strong> y si podr\u00eda ver el servicio expandirse\/evolucionar a\u00fan m\u00e1s. Ella me dijo que,<\/p>\n<blockquote><p><em>&#8220;Vemos el futuro en las aplicaciones m\u00f3viles, ya que el uso de internet se est\u00e1 moviendo r\u00e1pidamente de las computadoras y port\u00e1tiles a los dispositivos m\u00f3viles, y la necesidad de hacerlos seguros y privados est\u00e1 creciendo&#8221;.<\/em><\/p><\/blockquote>\n<p>Supongo que solo queda una cosa por decir; \u00a1Feliz cumplea\u00f1os Le VPN! \u00a1Celebremos con pastel de cumplea\u00f1os cifrado y globos de fiesta virtuales!<\/p>\n[vc_row][vc_column]<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-606a03ef7a1d278\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div data-id=\"mpc_callout-976a03ef7a1bf67\" class=\"mpc-callout mpc-init mpc-callout--style_1 \"><div class=\"mpc-callout__icon-wrap mpc-icon--image\"><div class=\"mpc-callout__icon\"><i class=\"mpc-transition \"><img decoding=\"async\" class=\"\" src=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2025\/09\/exclusive-deal.png\" width=\"100\" height=\"100\" alt=\"exclusive-deal\" title=\"exclusive-deal\" loading=\"lazy\"><\/i><\/div><\/div><div class=\"mpc-callout__content\"><h3 class=\"mpc-callout__heading mpc-typography--preset_1\">OFERTA EXCLUSIVA<\/h3><div data-id=\"mpc_divider-766a03ef7a1c018\" class=\"mpc-divider-wrap\"><div class=\"mpc-divider mpc-init mpc-align--center mpc-disable--left \"><div class=\"mpc-divider__line mpc-side--left\"><span><\/span><\/div><div class=\"mpc-divider__line mpc-side--right\"><span><\/span><\/div><\/div><\/div><div class=\"mpc-callout__description mpc-typography--preset_0\"><p style=\"padding-right: 20px;\">-78% EN PLANES DE 3 A&Ntilde;OS<\/p>\n<\/div><\/div><div class=\"mpc-callout__button\"><a href=\"https:\/\/www.le-vpn.com\/es\/comprar-vpn\/\" title=\"\" data-id=\"mpc_button-876a03ef7a1bfc7\" class=\"mpc-button mpc-init mpc-transition mpc-typography--preset_1 \"><div class=\"mpc-button__content mpc-effect-type--none mpc-effect-side--none\"><span class=\"mpc-button__title mpc-transition\">APROVECHA<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-766a03ef7a1c5d6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037373801\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>SIN REGISTROS<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1646323796922\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>SERVIDORES EN 100 UBICACIONES<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-796a03ef7a1c853\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037390158\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>P2P PERMITIDO<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037398008\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>F&Aacute;CIL DE USAR<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-436a03ef7a1ca88\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1622662058202\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>30 D&Iacute;AS DE GARANT&Iacute;A<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037416990\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>SOPORTE AMABLE<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-196a03ef7a1ccae\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037425450\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>ACEPTA BITCOIN<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037434475\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:11px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>VELOCIDADES ULTRA VELOCES<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-296a03ef7a1d924\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\r\n<\/div>[\/vc_column][\/vc_row]<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfRecuerdas ese gran evento que sucedi\u00f3 en 2010? No, no estoy hablando de que Apple haya lanzado el primer iPad, ni de que Dubai haya inaugurado el edificio m\u00e1s alto del mundo. Estoy hablando del nacimiento de la VPN en la que conf\u00edan millones de usuarios: Le VPN. Le VPN est\u00e1 celebrando 11 a\u00f1os brindando<\/p>\n","protected":false},"author":14,"featured_media":15485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_metadesc":"\u00a1Le VPN acaba de cumplir 11 a\u00f1os! Nos sumergimos en la historia de la VPN m\u00e1s confiable, los desaf\u00edos que enfrent\u00f3 y sus planes futuros.","footnotes":""},"categories":[599],"tags":[],"yst_prominent_words":[1109,1105,740,2931,703,5006,4563,8002,5929,5905,2929],"class_list":["post-15484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog_old"],"_links":{"self":[{"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/posts\/15484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/comments?post=15484"}],"version-history":[{"count":4,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/posts\/15484\/revisions"}],"predecessor-version":[{"id":15494,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/posts\/15484\/revisions\/15494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/media\/15485"}],"wp:attachment":[{"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/media?parent=15484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/categories?post=15484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/tags?post=15484"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/yst_prominent_words?post=15484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}