{"id":14301,"date":"2020-10-09T02:39:16","date_gmt":"2020-10-09T02:39:16","guid":{"rendered":"https:\/\/www.le-vpn.com\/es\/?p=14301"},"modified":"2020-10-09T02:39:16","modified_gmt":"2020-10-09T02:39:16","slug":"seguridad-cibernetica-iot","status":"publish","type":"post","link":"https:\/\/www.le-vpn.com\/es\/seguridad-cibernetica-iot\/","title":{"rendered":"Si Lo Conectas, Prot\u00e9gelo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>La l\u00ednea entre nuestra vida en l\u00ednea y nuestra vida fuera de l\u00ednea es cada vez m\u00e1s invisible. Vivimos en un mundo conectado, donde la mayor\u00eda de los dispositivos de nuestro hogar usan internet. Gran parte de las actividades que realizamos necesitan de un servicio de banda ancha o la conexi\u00f3n a wifi; compramos, vendemos, consultamos, nos suscribimos a cursos, estudiamos, trabajamos, y mucho, much\u00edsimo m\u00e1s. Estas son solo algunas de las razones para usar una <a href=\"https:\/\/www.le-vpn.com\/es\/\">VPN<\/a>. Aprende por qu\u00e9 es indispensable para tu hogar y para tu seguridad cibern\u00e9tica.<\/p>\n<h3>La Seguridad Cibern\u00e9tica Empieza en Casa<\/h3>\n<p>Si puedes, intenta hacer una lista de diez cosas que haces durante el d\u00eda y para las que no necesites usar internet, un buscador, o un dispositivo m\u00f3vil. Quiz\u00e1s sea el resultado de la costumbre y adquisici\u00f3n de h\u00e1bitos a lo largo de los a\u00f1os, pero seguramente todos coincidimos en que las cosas son realmente m\u00e1s f\u00e1ciles usando una conexi\u00f3n a internet.<\/p>\n<p>Estos son solo algunos de los dispositivos dom\u00e9sticos que pueden venir con conexi\u00f3n a internet:<\/p>\n<ul>\n<li>C\u00e1maras<\/li>\n<li>Cafeteras<\/li>\n<li>Esterillas para hacer yoga<\/li>\n<li>Luces<\/li>\n<li>Termostato<\/li>\n<li>Aire Acondicionado<\/li>\n<li>Microondas<\/li>\n<li>Aspiradoras<\/li>\n<li>Calefones<\/li>\n<li>Cerraduras<\/li>\n<li>Rociadores para el jard\u00edn<\/li>\n<li>Timbres<\/li>\n<\/ul>\n<p>Y muchos m\u00e1s\u2026 Debido a la gran cantidad de dispositivos que van incorporando la conexi\u00f3n a internet y se suman a la familia IoT, Internet de las Cosas, es importante conocer cu\u00e1les son los riesgos a los que estamos expuestos &#8211; las ventajas ya las conocemos.<\/p>\n<h3>Aprender a Usar Internet<\/h3>\n<p>Es importante resaltar que, el solo hecho de estar publicando en redes sociales o manejar Instagram, no nos da derecho a creer que somos expertos en tecnolog\u00eda.<\/p>\n<p>Para irnos a los extremos\u2026 Los ni\u00f1os y adolescentes, que suelen pasar horas frente a los dispositivos m\u00f3viles mirando videos de YouTube, tampoco son grandes conocedores de las redes. Al menos no lo son en cuanto a la seguridad cibern\u00e9tica se refiere. Por otro lado, muchos adultos mayores se han adaptado a la nueva tecnolog\u00eda y cuentan con perfiles en redes sociales. Sin embargo, la mayor\u00eda ignora c\u00f3mo sus cuentas y dispositivos est\u00e1n conectados entre s\u00ed. Para ampliar el abanico, muchos que no son ni ni\u00f1os, ni adolescentes, ni adultos mayores, tambi\u00e9n desconocen el cuidado que deber\u00edan tener.<\/p>\n<h3>Asegurar las Redes y los Dispositivos Evita Riesgos<\/h3>\n<p>Es l\u00f3gico decir que no debemos ser t\u00e9cnicos en computaci\u00f3n para usar internet. Pero cuidar nuestras conexiones y dispositivos en el hogar debe ser tan importante como el cuidado que tenemos de otras cosas. La realidad es que todos los dispositivos conectados en nuestra casa tienen un contacto con el exterior y pueden ser objetivo de ataques, virus, malware y otras cuestiones que afectan nuestra seguridad cibern\u00e9tica y privacidad.<\/p>\n<h4>La Informaci\u00f3n Personal<\/h4>\n<p>Uno de los mayores riesgos de los dispositivos de IoT es la p\u00e9rdida de la informaci\u00f3n personal. Si alguien robara los datos que guarda uno de esos aparatos, podr\u00edamos estar enfrent\u00e1ndonos a algo muy serio.<\/p>\n<p>Un reloj inteligente, por ejemplo, puede brindarle a un hacker m\u00e1s informaci\u00f3n de la que nosotros mismos sabemos sobre nosotros. El hackeo de un router puede ofrecer una largu\u00edsima lista de nuestros h\u00e1bitos de navegaci\u00f3n, conexiones, horarios, contactos, y mucho m\u00e1s. Y, como consecuencia, esa informaci\u00f3n perdida se puede convertir en dinero y alimento para quienes tienen intenciones de aprovecharla maliciosamente.<\/p>\n<h3>Mes de la Concientizaci\u00f3n sobre la Ciberseguridad<\/h3>\n<p>Este mes de la Concientizaci\u00f3n sobre la Seguridad Cibern\u00e9tica es un buen momento para empezar a cuidarnos y cuidar a nuestros seres queridos, as\u00ed como tambi\u00e9n, proteger nuestros dispositivos IoT y nuestro hogar.<\/p>\n<p>\u00bfDe qu\u00e9 manera?<\/p>\n<ul>\n<li>Manteniendo las m\u00e1quinas y dispositivos limpios. Es decir, practicando la ciberhigiene.<\/li>\n<li>Mejorando la seguridad de las cuentas de los sitios que visitamos.<\/li>\n<li>Pensando antes de publicar informaci\u00f3n personal.<\/li>\n<li>Haciendo copias de respaldo de archivos valiosos.<\/li>\n<li>Evitando compartir nuestra ubicaci\u00f3n y actividad cotidiana.<\/li>\n<li>Asegurando nuestros routers.<\/li>\n<li>Mejorando las contrase\u00f1as.<\/li>\n<li>Instalando una VPN en el router de nuestro hogar para llevar seguridad cibern\u00e9tica a todos los dispositivos conectados.<\/li>\n<\/ul>\n<h3>Prot\u00e9gete con Le VPN<\/h3>\n<p>Le VPN es campe\u00f3n del Mes de la Concientizaci\u00f3n sobre la Ciberseguridad. Como todos los a\u00f1os, y como lo hace d\u00eda a d\u00eda, trabaja para brindar seguridad, privacidad y calidad con su <a href=\"https:\/\/www.le-vpn.com\/es\/que-es-una-vpn\/\">servicio VPN<\/a>. Su objetivo principal es llevar la seguridad cibern\u00e9tica un paso m\u00e1s all\u00e1 y proteger a cada dispositivo, conexi\u00f3n y usuario del mundo. Sus sofisticados protocolos de grado militar y una larga trayectoria en la industria de la seguridad cibern\u00e9tica hacen de Le VPN un l\u00edder indiscutible. Protege tu hogar, tus dispositivos IoT, a tu familia y toda tu actividad en l\u00ednea con Le VPN.<\/p>\n[vc_row][vc_column]<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-956a0401bb3d93a\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div data-id=\"mpc_callout-586a0401bb3c840\" class=\"mpc-callout mpc-init mpc-callout--style_1 \"><div class=\"mpc-callout__icon-wrap mpc-icon--image\"><div class=\"mpc-callout__icon\"><i class=\"mpc-transition \"><img decoding=\"async\" class=\"\" src=\"https:\/\/www.le-vpn.com\/es\/wp-content\/uploads\/2025\/09\/exclusive-deal.png\" width=\"100\" height=\"100\" alt=\"exclusive-deal\" title=\"exclusive-deal\" loading=\"lazy\"><\/i><\/div><\/div><div class=\"mpc-callout__content\"><h3 class=\"mpc-callout__heading mpc-typography--preset_1\">OFERTA EXCLUSIVA<\/h3><div data-id=\"mpc_divider-976a0401bb3c8b6\" class=\"mpc-divider-wrap\"><div class=\"mpc-divider mpc-init mpc-align--center mpc-disable--left \"><div class=\"mpc-divider__line mpc-side--left\"><span><\/span><\/div><div class=\"mpc-divider__line mpc-side--right\"><span><\/span><\/div><\/div><\/div><div class=\"mpc-callout__description mpc-typography--preset_0\"><p style=\"padding-right: 20px;\">-78% EN PLANES DE 3 A&Ntilde;OS<\/p>\n<\/div><\/div><div class=\"mpc-callout__button\"><a href=\"https:\/\/www.le-vpn.com\/es\/comprar-vpn\/\" title=\"\" data-id=\"mpc_button-236a0401bb3c88c\" class=\"mpc-button mpc-init mpc-transition mpc-typography--preset_1 \"><div class=\"mpc-button__content mpc-effect-type--none mpc-effect-side--none\"><span class=\"mpc-button__title mpc-transition\">APROVECHA<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-976a0401bb3cd5c\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037373801\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>SIN REGISTROS<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1646323796922\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>SERVIDORES EN 100 UBICACIONES<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-446a0401bb3cf9b\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037390158\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>P2P PERMITIDO<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037398008\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>F&Aacute;CIL DE USAR<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-76a0401bb3d1b7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1622662058202\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>30 D&Iacute;AS DE GARANT&Iacute;A<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037416990\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>SOPORTE AMABLE<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 mpc-column\" data-column-id=\"mpc_column-346a0401bb3d3bf\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037425450\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:12px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>ACEPTA BITCOIN<\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1619037434475\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"font-size:11px;color:#444;text-transform: uppercase;margin-left:10px;\"><svg width=\"16\" style=\"vertical-align: -10%;margin-right:10px;\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 81.68 81.67\"><defs><style>.cls-1{fill:#7ec58e;}.cls-2{fill:#fff;}<\/style><\/defs><path class=\"cls-1\" d=\"M40.84,0A40.84,40.84,0,1,0,81.68,40.84,40.83,40.83,0,0,0,40.84,0Z\"><\/path><g id=\"done\"><g id=\"check-circle-outline\"><polygon class=\"cls-2\" points=\"18.69 39.75 13.55 44.89 30.07 61.41 66.79 24.69 61.65 19.55 30.07 51.13 18.69 39.75\"><\/polygon><\/g><\/g><\/svg>VELOCIDADES ULTRA VELOCES<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-546a0401bb3df41\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\r\n<\/div>[\/vc_column][\/vc_row]<\/div>","protected":false},"excerpt":{"rendered":"<p>La l\u00ednea entre nuestra vida en l\u00ednea y nuestra vida fuera de l\u00ednea es cada vez m\u00e1s invisible. Vivimos en un mundo conectado, donde la mayor\u00eda de los dispositivos de nuestro hogar usan internet. Gran parte de las actividades que realizamos necesitan de un servicio de banda ancha o la conexi\u00f3n a wifi; compramos, vendemos,<\/p>\n","protected":false},"author":4,"featured_media":14302,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_metadesc":"Los dispositivos IoT nos facilitan la vida, pero pueden ser un riesgo si no tomamos las medidas de protecci\u00f3n para la seguridad cibern\u00e9tica.","footnotes":""},"categories":[599],"tags":[],"yst_prominent_words":[5898,2345,1316,1633,6932,7911,6359,5005,5943,740,703,5006,1434,2645,3179,5949,2929],"class_list":["post-14301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog_old"],"_links":{"self":[{"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/posts\/14301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/comments?post=14301"}],"version-history":[{"count":1,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/posts\/14301\/revisions"}],"predecessor-version":[{"id":14303,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/posts\/14301\/revisions\/14303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/media\/14302"}],"wp:attachment":[{"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/media?parent=14301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/categories?post=14301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/tags?post=14301"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.le-vpn.com\/es\/wp-json\/wp\/v2\/yst_prominent_words?post=14301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}